{"id":14707,"date":"2024-05-20T17:34:33","date_gmt":"2024-05-20T23:34:33","guid":{"rendered":"https:\/\/hombresymujeresdelacasa.com\/home\/?p=14707"},"modified":"2024-05-20T17:34:38","modified_gmt":"2024-05-20T23:34:38","slug":"aprueba-sedatu-plan-de-ordenamiento-territorial-de-campeche","status":"publish","type":"post","link":"https:\/\/hombresymujeresdelacasa.com\/home\/aprueba-sedatu-plan-de-ordenamiento-territorial-de-campeche\/","title":{"rendered":"Aprueba Sedatu plan de Ordenamiento Territorial de Campeche"},"content":{"rendered":"\n<p>Por: Fernanda Hern\u00e1ndez<\/p>\n\n\n\n<p><em>El coordinador de Desarrollo Metropolitano de la Sedatu explic\u00f3 que el Programa busca asegurar un desarrollo sostenible y equilibrado en la entidad<\/em><\/p>\n\n\n\n<p>La&nbsp;<strong>Secretar\u00eda de Desarrollo Agrario, Territorial y Urbano<\/strong>&nbsp;(<strong>Sedatu<\/strong>) aprob\u00f3 el&nbsp;<strong>Programa Estatal de Ordenamiento Territorial y Desarrollo Urbano de Campeche<\/strong>, que busca dar certeza y equidad al uso de suelo; as\u00ed como conservar y mejorar las \u00e1reas de valor ambiental e identificar zonas de riesgo para los asentamientos humanos.<\/p>\n\n\n\n<p>Durante la tercera sesi\u00f3n ordinaria del Consejo Estatal de Ordenamiento Territorial y Desarrollo Urbano,&nbsp;<strong><a href=\"https:\/\/twitter.com\/alvarolomelicov\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">\u00c1lvaro Lomel\u00ed Covarrubias<\/a>, coordinador de Desarrollo Metropolitano y Movilidad de la Sedatu<\/strong>, destac\u00f3 que dicho documento tiene el prop\u00f3sito de asegurar un desarrollo sostenible y equilibrado en todas las regiones del estado.<\/p>\n\n\n\n<p>Lo anterior, mediante estrategias y proyectos que prevean un&nbsp;<strong>crecimiento urbano ordenado y sustentable<\/strong>&nbsp;para los pr\u00f3ximos 25 a\u00f1os. Por ello, se busca implementar pol\u00edticas de regulaci\u00f3n, mejoramiento y densificaci\u00f3n urbana; as\u00ed como de conservaci\u00f3n, protecci\u00f3n o restauraci\u00f3n ambiental y ecol\u00f3gica.<\/p>\n\n\n\n<p>\u201cEste programa estatal representa un compromiso firme con el desarrollo sostenible y equitativo para el estado de&nbsp;<strong>Campeche<\/strong>, estableciendo criterios generales y directrices claras a los municipios que les permitir\u00e1n tomar mejores decisiones para su territorio, generando certeza jur\u00eddica a la propiedad y a las inversiones, as\u00ed como utilizar al desarrollo urbano como una palanca para el desarrollo\u201d, se\u00f1al\u00f3 el funcionario.<\/p>\n\n\n\n<p>Cabe mencionar que, dentro del proceso de elaboraci\u00f3n del&nbsp;<strong>Programa Estatal<\/strong>, se integr\u00f3 la participaci\u00f3n de los habitantes, los sectores de la sociedad civil y los gremios de profesionistas a trav\u00e9s de talleres, encuestas y mesas de gobernanza con actores estrat\u00e9gicos.<\/p>\n\n\n\n<p>Adem\u00e1s, este programa a escala estatal se suma al&nbsp;<strong>Programa de Ordenamiento Territorial de la Regi\u00f3n Sur-Sureste<\/strong>&nbsp;(POT-RSSE), con \u00e9nfasis en el Tren Maya, publicado por la Sedatu en junio pasado.<\/p>\n\n\n\n<p>En ese sentido,&nbsp;<strong>Lomel\u00ed<\/strong>&nbsp;resalt\u00f3 que la implementaci\u00f3n del proyecto del Tren Maya en la regi\u00f3n sureste va acompa\u00f1ado de instrumentos de planeaci\u00f3n, ordenamiento territorial y desarrollo urbano en todas sus escalas.<\/p>\n\n\n\n<p>Asimismo, precis\u00f3 que el&nbsp;<strong>Programa Estatal de Campeche<\/strong>&nbsp;contemplan la elaboraci\u00f3n de&nbsp;<strong>10 Programas Municipales de Desarrollo Urbano<\/strong>&nbsp;en: Campeche, Seybaplaya, Candelaria, Hecelchak\u00e1n, Tenabo, Champot\u00f3n, Calkin\u00ed, El Carmen, Hopelch\u00e9n y Palizada, los cuales representan m\u00e1s del 75% del territorio estatal.<\/p>\n\n\n\n<p>Y, de igual manera, el funcionario de la Sedatu explic\u00f3 que el programa estatal contempla&nbsp;<strong>cuatro ejes principales<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Articulaci\u00f3n del desarrollo urbano con el ordenamiento ecol\u00f3gico<\/li>\n\n\n\n<li>Detonar el turismo y las actividades productivas locales<\/li>\n\n\n\n<li>Desarrollar proyectos integrales para el rescate, salvaguarda y divulgaci\u00f3n del patrimonio cultural inmaterial<\/li>\n\n\n\n<li>Consolidar el sistema urbano-rural con las principales ciudades, como Campeche, Carmen y Esc\u00e1rcega; e impulsar la consolidaci\u00f3n de los centros urbanos de Calkin\u00ed, Xpujil y Candelaria<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/hombresymujeresdelacasa.com\/home\/wp-content\/uploads\/2024\/05\/sedatu-campeche-768x576-1.jpeg\" alt=\"\" class=\"wp-image-14708\" srcset=\"https:\/\/hombresymujeresdelacasa.com\/home\/wp-content\/uploads\/2024\/05\/sedatu-campeche-768x576-1.jpeg 768w, https:\/\/hombresymujeresdelacasa.com\/home\/wp-content\/uploads\/2024\/05\/sedatu-campeche-768x576-1-300x225.jpeg 300w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p><a href=\"https:\/\/centrourbano.com\/revista\/author\/fernanda-hernandez\/\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Fernanda Hern\u00e1ndez El coordinador de Desarrollo Metropolitano de la Sedatu explic\u00f3 que el Programa busca asegurar un desarrollo sostenible y equilibrado en la entidad La&nbsp;Secretar\u00eda de Desarrollo Agrario, Territorial y Urbano&nbsp;(Sedatu) aprob\u00f3 el&nbsp;Programa Estatal de Ordenamiento Territorial y Desarrollo Urbano de Campeche, que busca dar certeza y equidad al uso de suelo; as\u00ed como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14709,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4],"tags":[33,6262,5193,6261,154],"class_list":["post-14707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-campeche","tag-crecimiento-urbano-ordenando-y-sustentable","tag-programa-de-ordenamiento-territorial-de-la-region-sur-sureste","tag-programa-estatal-de-desarrollo-territorial-y-desarrollo-urbano-de-campeche","tag-sedatu"],"_links":{"self":[{"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/posts\/14707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/comments?post=14707"}],"version-history":[{"count":1,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/posts\/14707\/revisions"}],"predecessor-version":[{"id":14710,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/posts\/14707\/revisions\/14710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/media\/14709"}],"wp:attachment":[{"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/media?parent=14707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/categories?post=14707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/tags?post=14707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}