{"id":12787,"date":"2023-08-29T13:35:07","date_gmt":"2023-08-29T19:35:07","guid":{"rendered":"https:\/\/hombresymujeresdelacasa.com\/home\/?p=12787"},"modified":"2023-08-29T13:35:14","modified_gmt":"2023-08-29T19:35:14","slug":"limite-de-tiempo-para-solicitar-la-devolucion-de-la-subcuenta-de-vivienda-infonavit","status":"publish","type":"post","link":"https:\/\/hombresymujeresdelacasa.com\/home\/limite-de-tiempo-para-solicitar-la-devolucion-de-la-subcuenta-de-vivienda-infonavit\/","title":{"rendered":"L\u00edmite de tiempo para solicitar la devoluci\u00f3n de la Subcuenta de Vivienda Infonavit"},"content":{"rendered":"\n<p>Por: Rebeca Romero <\/p>\n\n\n\n<p><em>Mientras la Subcuenta de Vivienda sea manejado por el Infonavit, generar\u00e1 rendimientos<\/em><\/p>\n\n\n\n<p>A trav\u00e9s de la&nbsp;<a href=\"https:\/\/centrourbano.com\/vivienda\/subcuenta-de-vivienda-infonavit\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Subcuenta de Vivienda<\/a>, el Instituto del Fondo Nacional de la Vivienda para los Trabajadores (Infonavit) busca brindarle a sus afiliados apoyo para la formaci\u00f3n de su patrimonio y su&nbsp;<strong>certeza econ\u00f3mica en su jubilaci\u00f3n<\/strong>.&nbsp;<\/p>\n\n\n\n<p>De manera que, cuando llegue el momento, si el trabajador no utiliz\u00f3 el ahorro para la compra de una vivienda, o ya liquid\u00f3 su cr\u00e9dito, puede<strong>&nbsp;solicitar la devoluci\u00f3n del total de su ahorro m\u00e1s los rendimientos que gener\u00f3<\/strong>&nbsp;su dinero durante los a\u00f1os de trabajo.<\/p>\n\n\n\n<p>Cabe se\u00f1alar que a diferencia de otras instituciones, Infonavit&nbsp;<strong>no cuenta con un plazo m\u00e1ximo para solicitar la devoluci\u00f3n<\/strong>&nbsp;de la Subcuenta de Vivienda. Esto se debe a que<strong>&nbsp;a pesar del tiempo, el ahorro estar\u00e1 a salvo.&nbsp;<\/strong><\/p>\n\n\n\n<p>No obstante, si despu\u00e9s de&nbsp;<strong>nueve a\u00f1os&nbsp;<\/strong>el jubilado no ha solicitado la devoluci\u00f3n del fondo, el Instituto le enviar\u00e1 por correo electr\u00f3nico o mensaje de texto un&nbsp;<strong>aviso para recordarle la situaci\u00f3n<\/strong>. Por ello es importante que todos los derechohabientes del Infonavit mantengan sus&nbsp;<strong>datos de contacto actualizados<\/strong>.<\/p>\n\n\n\n<p>Pero, en caso de que despu\u00e9s de nueve a\u00f1os el dinero no sea retirado, el organismo cuenta con una&nbsp;<strong>reserva financiera&nbsp;<\/strong>que hace posible que la<strong>&nbsp;Subcuenta de Vivienda contin\u00fae generando rendimientos.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Requisitos para la devoluci\u00f3n de la Subcuenta de Vivienda<\/h2>\n\n\n\n<p>El derechohabiente deber\u00e1 tramitar directamente su&nbsp;<strong>solicitud de devoluci\u00f3n en l\u00ednea a trav\u00e9s de&nbsp;<\/strong><a href=\"https:\/\/micuenta.infonavit.org.mx\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\"><strong>Mi Cuenta Infonavit<\/strong><\/a>. Para ello, el ahora jubilado deber\u00e1 contar con:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Firma electr\u00f3nica avanzada (e-firma) vigente ante el Servicio de Administraci\u00f3n Tributaria (SAT).<\/li>\n\n\n\n<li>Contar con CLABE de una cuenta bancaria a nombre del derechohabiente que acepte la cantidad de dinero a devolver.<\/li>\n\n\n\n<li>Presentar la resoluci\u00f3n de pensi\u00f3n expedida por el IMSS.<\/li>\n<\/ul>\n\n\n\n<p>Adem\u00e1s, en caso del fallecimiento del pensionado, el ahorro tampoco se pierde, pues puede ser solicitado por su pareja, padres, hijos, beneficiarios designados en la Afore o beneficiarios designados por los Tribunales Federales en materia laboral.<\/p>\n\n\n\n<p><a href=\"https:\/\/centrourbano.com\/author\/rebeca-romero\/\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Rebeca Romero Mientras la Subcuenta de Vivienda sea manejado por el Infonavit, generar\u00e1 rendimientos A trav\u00e9s de la&nbsp;Subcuenta de Vivienda, el Instituto del Fondo Nacional de la Vivienda para los Trabajadores (Infonavit) busca brindarle a sus afiliados apoyo para la formaci\u00f3n de su patrimonio y su&nbsp;certeza econ\u00f3mica en su jubilaci\u00f3n.&nbsp; De manera que, cuando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12788,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4],"tags":[102,826,541,177],"class_list":["post-12787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-infonavit","tag-mi-cuenta-infonavit","tag-subcuenta-de-vivienda","tag-vivienda"],"_links":{"self":[{"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/posts\/12787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/comments?post=12787"}],"version-history":[{"count":1,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/posts\/12787\/revisions"}],"predecessor-version":[{"id":12789,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/posts\/12787\/revisions\/12789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/media\/12788"}],"wp:attachment":[{"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/media?parent=12787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/categories?post=12787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/tags?post=12787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}