{"id":12188,"date":"2023-07-13T17:04:35","date_gmt":"2023-07-13T23:04:35","guid":{"rendered":"http:\/\/hombresymujeresdelacasa.com\/home\/?p=12188"},"modified":"2023-07-13T17:04:37","modified_gmt":"2023-07-13T23:04:37","slug":"entrega-gcdmx-sendero-seguro-dr-vertiz","status":"publish","type":"post","link":"https:\/\/hombresymujeresdelacasa.com\/home\/entrega-gcdmx-sendero-seguro-dr-vertiz\/","title":{"rendered":"Entrega GCDMX Sendero Seguro \u2018Dr. Vertiz\u2019"},"content":{"rendered":"\n<p>Por: Rebeca Romero <\/p>\n\n\n\n<p><em>El Sendero Seguro \u2018Dr. V\u00e9rtiz\u2019 forma parte de las acciones del GCDMX que buscan atender las&nbsp;causas que generan la violencia contra las mujeres<\/em><\/p>\n\n\n\n<p>El Gobierno de la Ciudad de M\u00e9xico (<a href=\"https:\/\/www.cdmx.gob.mx\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">GCDMX<\/a>) entreg\u00f3 el&nbsp;<strong>Sendero Seguro<\/strong>&nbsp;Camina Libre, Camina Segura&nbsp;<strong>\u2018Dr. V\u00e9rtiz\u2019<\/strong>, ubicado en la avenida del mismo nombre en la&nbsp;<strong>alcald\u00eda Cuauht\u00e9moc<\/strong>. El nuevo sendero forma parte del tramo que va de Arcos de Bel\u00e9n a Viaducto Miguel Alem\u00e1n.<\/p>\n\n\n\n<p>Durante un recorrido por el Sendero Seguro \u2018Dr. V\u00e9rtiz\u2019, Jes\u00fas Antonio Esteva Medina, titular de la Secretar\u00eda de Obras y Servicios (Sobse), se\u00f1al\u00f3 que la obra abarc\u00f3&nbsp;<strong>2.6 kil\u00f3metros<\/strong>&nbsp;(km), donde fueron restituidos 12,320 metros cuadrados (m\u00b2) de banquetas. Del mismo modo, la Sobse instal\u00f3 en el sendero 956 luminarias LED,&nbsp;<strong>6 T\u00f3tems de Seguridad<\/strong>, 276 bolardos y 12 cruces seguros.<\/p>\n\n\n\n<p>En su participaci\u00f3n, Ingrid G\u00f3mez Sarac\u00edbar, titular de la Secretar\u00eda de las Mujeres, explic\u00f3 que la instalaci\u00f3n y acondicionamiento de los coment\u00f3 que los Senderos Seguros Camina Libre, Camina Segura forman parte de las&nbsp;<strong>acciones del gobierno<\/strong>&nbsp;capitalino para<strong>&nbsp;atender a las causas que generan la violencia contra las mujeres.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cPensando en c\u00f3mo intervenir el espacio p\u00fablico para la seguridad, armon\u00eda y paz de las mujeres, es que surge la pol\u00edtica de rescate de Senderos Seguros, para que podamos caminar libres y seguras; es muy importante y forma parte de una pol\u00edtica mayor de protecci\u00f3n y de atenci\u00f3n a las causas por las que se da violencia. Esto solo es una parte, entendemos que hay muchas causas por las que puede existir violencia\u201d, platic\u00f3.<\/p><\/blockquote>\n\n\n\n<p>Por su parte, Mart\u00ed Batres Guadarrama, jefe de Gobierno de la Ciudad de M\u00e9xico resalt\u00f3 que adem\u00e1s de la instalaci\u00f3n del sendero, la administraci\u00f3n capitalina tambi\u00e9n trabaj\u00f3 en la&nbsp;<strong>recuperaci\u00f3n del espacio en el Parque de las Artes Pl\u00e1sticas.&nbsp;<\/strong><\/p>\n\n\n\n<p>En cuanto a los senderos, Esteva Medina record\u00f3 que el<strong>&nbsp;GCDMX ha instalado m\u00e1s de 700 km de&nbsp;<a href=\"https:\/\/centrourbano.com\/urbanismo\/gcdmx-sendero-camina-libre\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Senderos Camina Libre<\/a>,<\/strong>&nbsp;Camina Segura; adem\u00e1s, el Secretario estima que para finales de este a\u00f1o, la cifra llegue a 900 km.<\/p>\n\n\n\n<p><a href=\"https:\/\/centrourbano.com\/author\/rebeca-romero\/\" rel=\"nofollow noopener\" target=\"_blank\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Rebeca Romero El Sendero Seguro \u2018Dr. V\u00e9rtiz\u2019 forma parte de las acciones del GCDMX que buscan atender las&nbsp;causas que generan la violencia contra las mujeres El Gobierno de la Ciudad de M\u00e9xico (GCDMX) entreg\u00f3 el&nbsp;Sendero Seguro&nbsp;Camina Libre, Camina Segura&nbsp;\u2018Dr. V\u00e9rtiz\u2019, ubicado en la avenida del mismo nombre en la&nbsp;alcald\u00eda Cuauht\u00e9moc. El nuevo sendero forma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12189,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4],"tags":[5304,5305,5306,2152,5257,5303],"class_list":["post-12188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-alcaldia-cuauhtemoc","tag-camina-libre","tag-camina-segura","tag-gobierno-de-la-ciudad-de-mexico","tag-martin-batres-guadarrama","tag-sendero-seguro"],"_links":{"self":[{"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/posts\/12188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/comments?post=12188"}],"version-history":[{"count":1,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/posts\/12188\/revisions"}],"predecessor-version":[{"id":12190,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/posts\/12188\/revisions\/12190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/media\/12189"}],"wp:attachment":[{"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/media?parent=12188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/categories?post=12188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hombresymujeresdelacasa.com\/home\/wp-json\/wp\/v2\/tags?post=12188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}